{"id":2513,"date":"2024-02-28T02:03:08","date_gmt":"2024-02-28T02:03:08","guid":{"rendered":"https:\/\/ecuadoradventurestrip.com\/?page_id=2513"},"modified":"2024-04-17T03:47:56","modified_gmt":"2024-04-17T03:47:56","slug":"campo-alto-chimborazo","status":"publish","type":"page","link":"https:\/\/ecuadoradventurestrip.com\/en\/campo-alto-chimborazo\/","title":{"rendered":"CAMPO ALTO CHIMBORAZO"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2513\" class=\"elementor elementor-2513\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d437d82 elementor-section-full_width elementor-section-stretched banner-general elementor-section-height-full elementor-section-height-default elementor-section-items-middle\" data-id=\"d437d82\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2714,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/campoalto-1.jpg&quot;},{&quot;id&quot;:2715,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/campoalto-2.jpg&quot;},{&quot;id&quot;:2716,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/campoalto-3.jpg&quot;},{&quot;id&quot;:2717,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/campoalto-4.jpg&quot;},{&quot;id&quot;:2718,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/campoalto-5.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e7688e6\" data-id=\"7e7688e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-138cb249 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"138cb249\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c74f5f2\" data-id=\"6c74f5f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a93f51c elementor-widget elementor-widget-heading\" data-id=\"1a93f51c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CAMPO ALTO CHIMBORAZO<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64b3c19 elementor-section-full_width elementor-section-stretched elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"64b3c19\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26432d1\" data-id=\"26432d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99ead5b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99ead5b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a2559e3\" data-id=\"a2559e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ded9a2 elementor-widget__width-initial elementor-absolute elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"2ded9a2\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-1024x576.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-2716\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-3.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-540075b elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"540075b\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1024x576.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-2717\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-899e39e elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"899e39e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-351bd7d elementor-widget__width-initial elementor-absolute elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"351bd7d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c96a4ae\" data-id=\"c96a4ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a32e98 elementor-widget elementor-widget-heading\" data-id=\"3a32e98\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Why take this tour?<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aae186b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"aae186b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">This trekking is ideal for people who wish to walk higher than the normal route, here you must put on your mountain equipment, walking for approximately 2 hours and 30 minutes to the domes (Campo Alto) at 5350 meters above sea level.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">This tour is ideal for acclimatization and training before climbing to the summits of the volcanoes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890977f elementor-widget elementor-widget-heading\" data-id=\"890977f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Important<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-935d204 elementor-widget elementor-widget-text-editor\" data-id=\"935d204\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>We pick you up from your Hotel, airbnb, Terminal Terrestre or at the address indicated in RIOBAMBA, we can also pick you up in the city of Ba\u00f1os (additional price).<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a663a1 elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9a663a1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form-reservar\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bf5700 elementor-widget elementor-widget-spacer\" data-id=\"1bf5700\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-765a4b33 caja-contenido elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"765a4b33\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a983a13\" data-id=\"4a983a13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d1d1aec elementor-widget elementor-widget-heading\" data-id=\"6d1d1aec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Important<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-268a664 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"268a664\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f6cdc26\" data-id=\"f6cdc26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3c9dff elementor-widget elementor-widget-text-editor\" data-id=\"f3c9dff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>We pick you up from your Hotel, airbnb, Terminal Terrestre or at the address indicated in RIOBAMBA, we can also pick you up in the city of Ba\u00f1os (additional price).<\/li><li>Videos with a Go Pro Hero 12 camera.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-394b6d7 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"394b6d7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1527ae0\" data-id=\"1527ae0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35533e3 elementor-widget elementor-widget-heading\" data-id=\"35533e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Details<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0cea32 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b0cea32\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5b19bfb\" data-id=\"5b19bfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc14ae6 elementor-widget elementor-widget-text-editor\" data-id=\"dc14ae6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>PRICE:<\/strong> $80 X person (minimum 2 persons) discount for 3 and 4 persons, if you travel alone, ask us and we will help you.<\/p><p><strong>DURATION:<\/strong> From 8am-5pm<\/p><p><strong>AVAILABILITY:<\/strong> Every day<\/p><p><strong>PLACE OF DEPARTURE:<\/strong> Riobamba, we pick you up from your hotel, airbnb, bus station, bus station, etc.<\/p><p><strong>Optional<\/strong> (We can pick you up in the city of Ba\u00f1os, additional price $20 per person, minimum 2 persons)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7908d4b caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7908d4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cfc06e9\" data-id=\"cfc06e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3172790 elementor-widget elementor-widget-heading\" data-id=\"3172790\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Itinerary<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dbefba4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dbefba4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-973244f\" data-id=\"973244f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-007f4e9 elementor-widget elementor-widget-heading\" data-id=\"007f4e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Day 1<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aacfd9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5aacfd9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">08:00 Pick up at your Hotel, Riobamba<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">08:40 Typical Riobamba drink (canelazo)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">09:30 Arrival and registration at the Chimborazo Fauna Reserve (4300 masl)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10:00 Hike from the first Hermanos Carriel refuge (4800 masl) to Campo Alto (domes at 5350 masl).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">12:30 Arrival to Campo Alto (5350masl). Time for tea and pictures<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">13:30 Descent to the parking lot of the first refuge 4800 masl.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">15:30 Visit to the Chorrera de San Juan (Chimborazo canyon with heights between 30-80m).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">16:00 Lunch<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">17:00 End of Tour<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1fa7b48\" data-id=\"1fa7b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fec92f7 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"fec92f7\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2513 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"fec92f7\" data-elementor-lightbox-title=\"campoalto-5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjcxOCwidXJsIjoiaHR0cHM6XC9cL2VjdWFkb3JhZHZlbnR1cmVzdHJpcC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9jYW1wb2FsdG8tNS5qcGciLCJzbGlkZXNob3ciOiJmZWM5MmY3In0%3D\" data-rel=\"iLightbox[postimages]\" data-title=\"campoalto-5\" data-caption=\"\" href='https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5.jpg 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-3541ae1 elementor-widget elementor-widget-heading\" data-id=\"3541ae1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAMPO ALTO CHIMBORAZO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b155668 caja-contenido-salidas elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b155668\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4f3da9\" data-id=\"d4f3da9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22796ba elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"22796ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-02ac100\" data-id=\"02ac100\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9464880 elementor-widget elementor-widget-text-editor\" data-id=\"9464880\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Outputs:<\/h2><p>Every day, by reservation.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a900d37\" data-id=\"a900d37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af83be9 elementor-widget elementor-widget-text-editor\" data-id=\"af83be9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Includes:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7559d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ec7559d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Round trip transportation from Riobamba<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tourist Guide<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Personal equipment (helmet, walking sticks) if snow is present, crampons and gaiters<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Safety equipment<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lunch (Soup, main course, dessert) or vegetarian<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Visit to the Chimborazo Canyon<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entry permits to the Chimborazo Fauna Production Reserve<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Typical cocktail (Canelazo)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Traditional masks for photos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Video Photos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-999fb4c\" data-id=\"999fb4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b8b208 elementor-widget elementor-widget-text-editor\" data-id=\"0b8b208\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Does not include:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4c87f0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b4c87f0\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Beverages<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Iva (12 % value added tax) only for Ecuadorians if they want an invoice.)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lodging in Riobamba<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tips<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Snack<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7afc707 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7afc707\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b988b72\" data-id=\"b988b72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6fe2535 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6fe2535\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b96330d\" data-id=\"b96330d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca308a3 elementor-widget elementor-widget-text-editor\" data-id=\"ca308a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>How to book:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea58dd3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ea58dd3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Send a WhatsApp to (+593) 99-823-6014 or an email to info@ecuadoradventurestrip.com with the following specifications: Name of the tour, date of the tour, number of people, first and last name, ID or passport number, city or country of origin.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Once we receive the information we will coordinate the details of the trip and payment methods.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">The payment must be made with the advance payment of 50% of the value. Do not forget to send proof of payment to WhatsApp (+593) 99-823-6014 or email info@ecuadortravelstrip.com.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed205a elementor-widget elementor-widget-text-editor\" data-id=\"4ed205a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Important:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25e8188 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"25e8188\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">It is a private and exclusive program for couples, friends or families of 1, 2, 3 or 4 people in a vehicle at the most and if there are more people, another transport with another guide. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23ba153 elementor-widget elementor-widget-text-editor\" data-id=\"23ba153\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>What to bring:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec734e1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ec734e1\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comfortable walking shoes or boots, preferably trekking shoes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comfortable windproof or waterproof and warm clothes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chocolates, energy drinks and water<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sunscreen, a lightweight backpack to store extra clothing for windy weather<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11b40d0 elementor-widget elementor-widget-text-editor\" data-id=\"11b40d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Important:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9e99b elementor-widget elementor-widget-text-editor\" data-id=\"3f9e99b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>You can buy cap, glasses, gloves, souvenirs at the office in Riobamba before leaving.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b129d11\" data-id=\"b129d11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-09ae1d0 caja-formulario-tours\" data-id=\"09ae1d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0f1e9 elementor-widget elementor-widget-text-editor\" data-id=\"9c0f1e9\" data-element_type=\"widget\" id=\"form-reservar\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2><strong><span style=\"color: #0000ff;\">Book now<\/span><\/strong><\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-064cafa elementor-widget elementor-widget-text-editor\" data-id=\"064cafa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f807-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"807\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wp-json\/wp\/v2\/pages\/2513\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact Form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2513#wpcf7-f807-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"807\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f807-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.3\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name *\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"correo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" value=\"\" type=\"email\" name=\"correo\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone *\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"fecha\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required walcf7-datepicker\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Date: 0000-00-00 *\" value=\"\" type=\"text\" name=\"fecha\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"adultos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adults *\" value=\"\" type=\"text\" name=\"adultos\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ninnos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Children: under 10 y.o. *\" value=\"\" type=\"text\" name=\"ninnos\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"comentarios\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Comments\" value=\"\" type=\"text\" name=\"comentarios\" \/><\/span>\n<\/p>\n<p>Type this code: <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"433103726\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/wpcf7_captcha\/433103726.png\" \/><span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap tour\" data-name=\"tour\"><input type=\"hidden\" name=\"tour\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"CAMPO ALTO CHIMBORAZO\"><\/span>\n<p>* Required fields\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enquire\" \/>\n<\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Close\">\u00d7<\/button><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CAMPO ALTO CHIMBORAZO Why take this tour? This trekking [...]<\/p>","protected":false},"author":2,"featured_media":208,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2513","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n<\/title>\n<meta name=\"description\" content=\"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecuadoradventurestrip.com\/en\/campo-alto-chimborazo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecuadoradventurestrip.com\/en\/campo-alto-chimborazo\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo - Ecuador Adventures Trip\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecuadoradventurestrip\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T03:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/\",\"name\":\"Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg\",\"datePublished\":\"2024-02-28T02:03:08+00:00\",\"dateModified\":\"2024-04-17T03:47:56+00:00\",\"description\":\"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.\",\"breadcrumb\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Tours VIP al Chimborazo desde Riobamba\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecuadoradventurestrip.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMPO ALTO CHIMBORAZO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"description\":\"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador\",\"publisher\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"width\":5000,\"height\":5000,\"caption\":\"Turismo - Ecuador Adventures Trip\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecuadoradventurestrip\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n","description":"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecuadoradventurestrip.com\/en\/campo-alto-chimborazo\/","og_locale":"en_US","og_type":"article","og_title":"Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n","og_description":"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.","og_url":"https:\/\/ecuadoradventurestrip.com\/en\/campo-alto-chimborazo\/","og_site_name":"Turismo - Ecuador Adventures Trip","article_publisher":"https:\/\/www.facebook.com\/ecuadoradventurestrip","article_modified_time":"2024-04-17T03:47:56+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/","url":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/","name":"Tour al Chimborazo desde Riobamba Ecuador caminatas refugios volc\u00e1n","isPartOf":{"@id":"https:\/\/ecuadoradventurestrip.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage"},"thumbnailUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg","datePublished":"2024-02-28T02:03:08+00:00","dateModified":"2024-04-17T03:47:56+00:00","description":"Tour al Chimborazo es el mejor tour para conocer el volcan mas alto del Ecuador reserva ahora este tour, cerca de Riobamba.","breadcrumb":{"@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#primaryimage","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-4.jpg","width":1800,"height":1200,"caption":"Tours VIP al Chimborazo desde Riobamba"},{"@type":"BreadcrumbList","@id":"https:\/\/ecuadoradventurestrip.com\/campo-alto-chimborazo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecuadoradventurestrip.com\/"},{"@type":"ListItem","position":2,"name":"CAMPO ALTO CHIMBORAZO"}]},{"@type":"WebSite","@id":"https:\/\/ecuadoradventurestrip.com\/#website","url":"https:\/\/ecuadoradventurestrip.com\/","name":"Turismo - Ecuador Adventures Trip","description":"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador","publisher":{"@id":"https:\/\/ecuadoradventurestrip.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecuadoradventurestrip.com\/#organization","name":"Turismo - Ecuador Adventures Trip","url":"https:\/\/ecuadoradventurestrip.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","width":5000,"height":5000,"caption":"Turismo - Ecuador Adventures Trip"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecuadoradventurestrip"]}]}},"_links":{"self":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":0,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/2513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/media\/208"}],"wp:attachment":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/media?parent=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}