{"id":3037,"date":"2024-06-26T03:58:47","date_gmt":"2024-06-26T03:58:47","guid":{"rendered":"https:\/\/ecuadoradventurestrip.com\/?page_id=3037"},"modified":"2024-06-26T04:25:38","modified_gmt":"2024-06-26T04:25:38","slug":"ecuador-7-dias","status":"publish","type":"page","link":"https:\/\/ecuadoradventurestrip.com\/en\/ecuador-7-days\/","title":{"rendered":"Ecuador 7 Days"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3037\" class=\"elementor elementor-3037\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d437d82 elementor-section-full_width elementor-section-stretched banner-general elementor-section-height-full elementor-section-height-default elementor-section-items-middle\" data-id=\"d437d82\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:3039,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/banners-17.jpg&quot;},{&quot;id&quot;:3022,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/banners-2.jpg&quot;},{&quot;id&quot;:3023,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/banners-1.jpg&quot;},{&quot;id&quot;:3025,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/banners-3.jpg&quot;},{&quot;id&quot;:2945,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/foto-3.jpeg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02d9329\" data-id=\"02d9329\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d48295 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"6d48295\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba1ea3d\" data-id=\"ba1ea3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f075744 elementor-widget elementor-widget-heading\" data-id=\"f075744\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">VOLCANOES-CAMPING-BATHS-SELVA <\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7455e0d elementor-widget elementor-widget-heading\" data-id=\"7455e0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Why take this TRIP?<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a87585b elementor-widget elementor-widget-text-editor\" data-id=\"a87585b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>In this trip you will know and enjoy volcanoes, lagoons, waterfalls, mountains, rainforest, secondary jungle, national parks, camping, trekking in the mountains, visiting indigenous culture, gastronomy, folklore of Ecuador.<\/li><li>This trip is ideal for couples, groups of adventurous friends and families, who wish to camp, hike, sleep in the volcanoes surrounded by nature and enjoy adventure sports, hiking in the jungle.<\/li><li>If you want 3 or 4 days or more than 7 days we coordinate, (different price).<\/li><li>We can coordinate the meeting place such as QUITO airport, hotels near Quito airport or hotel in Quito.<\/li><li>Each tour includes lunches, transportation, entrance fees to the indicated places, and the tour guide.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9930416 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9930416\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52ed1b7\" data-id=\"52ed1b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-785f996 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"785f996\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbe78ba\" data-id=\"fbe78ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c2991f elementor-widget__width-initial elementor-absolute elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7c2991f\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-3023\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee189cd elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"ee189cd\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-1024x576.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-3039\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-17.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab453d elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7ab453d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11cbcf0 elementor-widget__width-initial elementor-absolute elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"11cbcf0\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e8ae550\" data-id=\"e8ae550\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c9d46 elementor-widget elementor-widget-heading\" data-id=\"39c9d46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Important<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f7ba01 elementor-widget elementor-widget-text-editor\" data-id=\"5f7ba01\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><p>We pick you up from any Hotel, located in the planned circuit, Hotels in the cities near the tourist destinations.<\/p><\/li><li><p>If you arrive at the Quito airport in the morning until 09:00 am we start the tour to the first tourist destination.<\/p><\/li><li><p>If you arrive in the afternoon or evening at the AIRPORT, we can pick you up and take you to the city or town of first tourist destination (additional price) transfer.<\/p><\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7421ea elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e7421ea\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form-reservar\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3f72b6 elementor-widget elementor-widget-spacer\" data-id=\"c3f72b6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59902d5 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59902d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec4c3e1\" data-id=\"ec4c3e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4cd8a7f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4cd8a7f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-da1f8cf\" data-id=\"da1f8cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a48cee6 elementor-widget elementor-widget-text-editor\" data-id=\"a48cee6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Details:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6583f1c elementor-widget elementor-widget-text-editor\" data-id=\"6583f1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>PRICE:<\/strong> $750 per person, Minimum 2 persons. Discount from 3 and 4 persons<\/p><p><strong>DURATION:<\/strong> 7 days<\/p><p><strong>AVAILABILITY:<\/strong> Every day<\/p><p><strong>PLACE OF DEPARTURE:<\/strong> QUITO airport until 9am, Hotels near Quito airport or hotel in Quito.<\/p><p><strong>PLACE OF COMPLETION:<\/strong> Ba\u00f1os de Agua Santa or Riobamba, these cities are 3 hours by bus from Quito.<br \/><br \/><strong>Optional (We can drop you off in Quito, additional price)<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38c5afa caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38c5afa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bc8757\" data-id=\"4bc8757\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7937559 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7937559\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-daf7feb\" data-id=\"daf7feb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-245cb4d elementor-widget elementor-widget-text-editor\" data-id=\"245cb4d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>QUILOTOA LAGOON Day 1:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0639c elementor-widget elementor-widget-text-editor\" data-id=\"fb0639c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>-Tour to Quilotoa<\/strong><\/p><p>(hike down to the Quilotoa lagoon, kayak in the lagoon, shalala viewpoint)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bfe812b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfe812b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ba3018\" data-id=\"6ba3018\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63037f6 elementor-widget elementor-widget-image\" data-id=\"63037f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-1024x683.jpg\" class=\"attachment-large size-large wp-image-1094\" alt=\"Quilotoa\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-quilotoa-2.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1318e03\" data-id=\"1318e03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9b1f39 elementor-widget elementor-widget-image\" data-id=\"b9b1f39\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/elementor\/thumbs\/Foto-3-1-qy1jd8a5wgy2itkipxunz00kzqthz9zs65h8elz7y8.jpeg\" title=\"Photo 3...\" alt=\"Photo 3...\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20a2721 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20a2721\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2da34e\" data-id=\"d2da34e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb103a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb103a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6bc6128\" data-id=\"6bc6128\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8adf163 elementor-widget elementor-widget-text-editor\" data-id=\"8adf163\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>VOLCAN COTOPAXI Day 2:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-718b2f2 elementor-widget elementor-widget-text-editor\" data-id=\"718b2f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>-Tour to the Cotopaxi Volcano.<\/strong><\/p><p>(hike to Refugio Jos\u00e9 Rivas 4800masl, Limpio Pungo lagoon, Limpio Pungo lake)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c039247 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c039247\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07c8e36\" data-id=\"07c8e36\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e284504 elementor-widget elementor-widget-image\" data-id=\"e284504\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-1024x576.jpg\" class=\"attachment-large size-large wp-image-3022\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1b81a1f\" data-id=\"1b81a1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63dc213 elementor-widget elementor-widget-image\" data-id=\"63dc213\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-1024x576.jpg\" class=\"attachment-large size-large wp-image-3025\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-3.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d903059 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d903059\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54050c1\" data-id=\"54050c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c9f7da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c9f7da\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e30e9bd\" data-id=\"e30e9bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01b3977 elementor-widget elementor-widget-text-editor\" data-id=\"01b3977\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>CHIMBORAZO VOLCANO Day 3:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc95f2b elementor-widget elementor-widget-text-editor\" data-id=\"bc95f2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Options:<\/strong><\/p><p>-Tour to Chimborazo, (hiking refuges, lagoon of the condor 5100masl).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7592fb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7592fb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-06eed19\" data-id=\"06eed19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3a9190 elementor-widget elementor-widget-image\" data-id=\"f3a9190\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-1024x768.jpeg\" class=\"attachment-large size-large wp-image-2946\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-200x150.jpeg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-300x225.jpeg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-400x300.jpeg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-600x450.jpeg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-768x576.jpeg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-800x600.jpeg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-1024x768.jpeg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4-1200x900.jpeg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/foto-4.jpeg 1210w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-02f0e7e\" data-id=\"02f0e7e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c5554 elementor-widget elementor-widget-image\" data-id=\"56c5554\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-1024x768.jpeg\" class=\"attachment-large size-large wp-image-2949\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-200x150.jpeg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-300x225.jpeg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-400x300.jpeg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-600x450.jpeg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-768x576.jpeg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-800x600.jpeg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-1024x768.jpeg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2-1200x900.jpeg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/fotos-2.jpeg 1210w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bcc251 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bcc251\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b36101\" data-id=\"5b36101\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7f057a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f057a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ee726f9\" data-id=\"ee726f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c78e7d3 elementor-widget elementor-widget-text-editor\" data-id=\"c78e7d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>-Mountain biking Chimborazo, (hiking refuges plus downhill biking).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea07ab3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea07ab3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-148dd87\" data-id=\"148dd87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6c5f27 elementor-widget elementor-widget-image\" data-id=\"c6c5f27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-967\" alt=\"Chimborazo Bicycles\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-1.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e63a5e6\" data-id=\"e63a5e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9a4031 elementor-widget elementor-widget-image\" data-id=\"a9a4031\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-1024x683.jpg\" class=\"attachment-large size-large wp-image-966\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-bicicleta-2.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c10657f caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c10657f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a3a5dc\" data-id=\"3a3a5dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4a6a4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4a6a4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5f06498\" data-id=\"5f06498\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ac64ba elementor-widget elementor-widget-text-editor\" data-id=\"2ac64ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>-Campo Alto 5350 masl (trekking to the domes, beginning of high mountain)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a298a7a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a298a7a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-98f63a2\" data-id=\"98f63a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a313ad3 elementor-widget elementor-widget-image\" data-id=\"a313ad3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1024x576.jpg\" class=\"attachment-large size-large wp-image-2718\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-5.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a1d728\" data-id=\"7a1d728\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ce902a elementor-widget elementor-widget-image\" data-id=\"8ce902a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1024x576.jpg\" class=\"attachment-large size-large wp-image-2717\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-200x113.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-300x169.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-400x225.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-600x338.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-768x432.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-800x450.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1024x576.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1200x675.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4-1536x864.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/03\/campoalto-4.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40b1da2 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40b1da2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-957418f\" data-id=\"957418f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11aa6b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11aa6b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0ff38f1\" data-id=\"0ff38f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9eb0ba elementor-widget elementor-widget-text-editor\" data-id=\"c9eb0ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>VOLCAN EL ALTAR Day 4-5<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5477b92 elementor-widget elementor-widget-text-editor\" data-id=\"5477b92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>(2 DAYS 1 NIGHT)<\/strong><\/p><p>- Laguna Amarilla trekking tour, El Altar volcano<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-622aa1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"622aa1f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ee72efb\" data-id=\"ee72efb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b75ff27 elementor-widget elementor-widget-image\" data-id=\"b75ff27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-1024x683.jpg\" class=\"attachment-large size-large wp-image-327\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/banner-slide-5.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a8ec60\" data-id=\"5a8ec60\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8923b4c elementor-widget elementor-widget-image\" data-id=\"8923b4c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-2449\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/02\/glaciares-banner-1.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-282d2fa caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"282d2fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6346140\" data-id=\"6346140\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ceef9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ceef9a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4325df7\" data-id=\"4325df7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-906f509 elementor-widget elementor-widget-text-editor\" data-id=\"906f509\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>HOLY WATER BATHS Day 4<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47c6c12 elementor-widget elementor-widget-text-editor\" data-id=\"47c6c12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Options:<\/strong><\/p><p>-Tour to Ba\u00f1os de Agua Santa, (Pailon del Diablo waterfall, End of the World Swing, Machay waterfall, Waterfall Route, Tarabita).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ee03c07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee03c07\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a497101\" data-id=\"a497101\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-577baa3 elementor-widget elementor-widget-image\" data-id=\"577baa3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/elementor\/thumbs\/foto-3-qy1jhzcsgbga1bczy1cgpvvobmj9qtqksm148ae60w.jpeg\" title=\"photo 3\" alt=\"photo 3\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bdcd9c9\" data-id=\"bdcd9c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84bf84d elementor-widget elementor-widget-image\" data-id=\"84bf84d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-1024x683.jpg\" class=\"attachment-large size-large wp-image-2920\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-22.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4fa85a caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4fa85a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac06554\" data-id=\"ac06554\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0a652a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a652a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62a49b8\" data-id=\"62a49b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1463e2f elementor-widget elementor-widget-text-editor\" data-id=\"1463e2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>-Rafting in Ba\u00f1os + Tour Ba\u00f1os (rafting, pail\u00f3n del Diablo, swing at the end of the world) additional price of rafting $20 dollars per person<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0d3ab2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0d3ab2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f3325b\" data-id=\"2f3325b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa256ac elementor-widget elementor-widget-image\" data-id=\"aa256ac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-1024x682.jpg\" class=\"attachment-large size-large wp-image-1599\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-1024x682.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/rafting-foto-vertical.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3d1426\" data-id=\"b3d1426\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16eb5c1 elementor-widget elementor-widget-image\" data-id=\"16eb5c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-2902\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/04\/tour-bannos-1.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75cfbc4 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75cfbc4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a0d2ab\" data-id=\"7a0d2ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-331af67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"331af67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0e51e88\" data-id=\"0e51e88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-666edeb elementor-widget elementor-widget-text-editor\" data-id=\"666edeb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>-Canyoning Ba\u00f1os + Ba\u00f1os Tour (waterfall descent, Devil's Pylon, End of the World Swing) additional canyoning price $30 per person.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5657187 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5657187\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f896899\" data-id=\"f896899\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f25764 elementor-widget elementor-widget-image\" data-id=\"8f25764\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-1024x683.jpg\" class=\"attachment-large size-large wp-image-1701\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-cashaurco-3.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c15e876\" data-id=\"c15e876\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8668bd9 elementor-widget elementor-widget-image\" data-id=\"8668bd9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-1024x683.jpg\" class=\"attachment-large size-large wp-image-988\" alt=\"Ba\u00f1os\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/02\/banner-tour-banos-4.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0b8857a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b8857a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c9476c\" data-id=\"3c9476c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dd5f8f elementor-widget elementor-widget-text-editor\" data-id=\"4dd5f8f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We finish in the city of Ba\u00f1os de Agua Santa or the city of Riobamba, <br \/>You can continue the trip to Quito by public bus the next day, which is 3 hours away from these two cities.<br \/>Or we have a transfer to Quito or to the airport (you can ask for the additional price).<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f61682 caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f61682\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a79a990\" data-id=\"a79a990\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-775504b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"775504b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0be75bb\" data-id=\"0be75bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef3a112 elementor-widget elementor-widget-text-editor\" data-id=\"ef3a112\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>SELVA PUYO Day 5<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-149f15e elementor-widget elementor-widget-text-editor\" data-id=\"149f15e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>-Puyo jungle tour<\/strong> (Puyo jungle hike, canoe ride, community visit, jungle viewpoint)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84f502f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84f502f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-194a6b1\" data-id=\"194a6b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e954a8e elementor-widget elementor-widget-image\" data-id=\"e954a8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-1290\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-1.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a87b26b\" data-id=\"a87b26b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93ab21a elementor-widget elementor-widget-image\" data-id=\"93ab21a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-1024x683.jpg\" class=\"attachment-large size-large wp-image-1286\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-tour-selvapuyo-5.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68b14fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68b14fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-60ef18a\" data-id=\"60ef18a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0193b1b elementor-widget elementor-widget-text-editor\" data-id=\"0193b1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We finish in the city of Ba\u00f1os de Agua Santa or the city of Riobamba.<\/p><p>You can continue the trip to Quito by public bus the next day, which is 3 hours away from these two cities.<\/p><p>Or we have a transfer to Quito or to the airport <strong>(you can ask for the additional price) <\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>VOLCANES-CAMPING-BA\u00d1OS-SELVA Why take this TRIP? On this trip you will [...]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3037","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip<\/title>\n<meta name=\"description\" content=\"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecuadoradventurestrip.com\/en\/ecuador-7-days\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip\" \/>\n<meta property=\"og:description\" content=\"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecuadoradventurestrip.com\/en\/ecuador-7-days\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo - Ecuador Adventures Trip\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecuadoradventurestrip\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-26T04:25:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/\",\"name\":\"Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip\",\"isPartOf\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg\",\"datePublished\":\"2024-06-26T03:58:47+00:00\",\"dateModified\":\"2024-06-26T04:25:38+00:00\",\"description\":\"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol\",\"breadcrumb\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecuadoradventurestrip.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecuador 7 D\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"description\":\"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador\",\"publisher\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"width\":5000,\"height\":5000,\"caption\":\"Turismo - Ecuador Adventures Trip\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecuadoradventurestrip\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip","description":"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecuadoradventurestrip.com\/en\/ecuador-7-days\/","og_locale":"en_US","og_type":"article","og_title":"Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip","og_description":"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol","og_url":"https:\/\/ecuadoradventurestrip.com\/en\/ecuador-7-days\/","og_site_name":"Turismo - Ecuador Adventures Trip","article_publisher":"https:\/\/www.facebook.com\/ecuadoradventurestrip","article_modified_time":"2024-06-26T04:25:38+00:00","og_image":[{"url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/","url":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/","name":"Ecuador 7 D\u00edas - Turismo - Ecuador Adventures Trip","isPartOf":{"@id":"https:\/\/ecuadoradventurestrip.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg","datePublished":"2024-06-26T03:58:47+00:00","dateModified":"2024-06-26T04:25:38+00:00","description":"Ba\u00f1os Ecuador, Los mejores tours en Ba\u00f1os de Agua Santa Ecuador, adrenalina, diversi\u00f3n tour delas cascadas, casa del \u00c1rbol","breadcrumb":{"@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#primaryimage","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2024\/06\/banners-1-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ecuadoradventurestrip.com\/ecuador-7-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecuadoradventurestrip.com\/"},{"@type":"ListItem","position":2,"name":"Ecuador 7 D\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/ecuadoradventurestrip.com\/#website","url":"https:\/\/ecuadoradventurestrip.com\/","name":"Turismo - Ecuador Adventures Trip","description":"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador","publisher":{"@id":"https:\/\/ecuadoradventurestrip.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecuadoradventurestrip.com\/#organization","name":"Turismo - Ecuador Adventures Trip","url":"https:\/\/ecuadoradventurestrip.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","width":5000,"height":5000,"caption":"Turismo - Ecuador Adventures Trip"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecuadoradventurestrip"]}]}},"_links":{"self":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/3037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/comments?post=3037"}],"version-history":[{"count":0,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/3037\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/media?parent=3037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}