{"id":421,"date":"2021-01-28T19:43:19","date_gmt":"2021-01-28T19:43:19","guid":{"rendered":"https:\/\/ecuadoradventurestrip.com\/?page_id=421"},"modified":"2021-03-22T16:42:41","modified_gmt":"2021-03-22T16:42:41","slug":"tour-canyoning-rio-blanco","status":"publish","type":"page","link":"https:\/\/ecuadoradventurestrip.com\/en\/rio-blanco-canyoning-tour\/","title":{"rendered":"Rio Blanco Canyoning Tour"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"421\" class=\"elementor elementor-421\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d437d82 elementor-section-full_width elementor-section-stretched banner-general elementor-section-height-default elementor-section-height-default\" data-id=\"d437d82\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1714,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/banner-rioblanco-6.jpg&quot;},{&quot;id&quot;:1713,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/banner-rioblanco-7.jpg&quot;},{&quot;id&quot;:1521,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/banner-rioblanco-3.jpg&quot;},{&quot;id&quot;:1520,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/banner-rioblanco-4.jpg&quot;},{&quot;id&quot;:1519,&quot;url&quot;:&quot;https:\\\/\\\/ecuadoradventurestrip.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/banner-rioblanco-5.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e7688e6\" data-id=\"7e7688e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b88aa7 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4b88aa7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-564247d\" data-id=\"564247d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e1d940 elementor-widget elementor-widget-heading\" data-id=\"1e1d940\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Canyoning Rio Blanco - Ba\u00f1os<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2260b8 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f2260b8\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bed0c6b\" data-id=\"bed0c6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed9db34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed9db34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd50333\" data-id=\"cd50333\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d78e2be elementor-widget__width-initial elementor-absolute elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"d78e2be\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-1524\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2202267 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"2202267\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-1024x683.jpg\" class=\"elementor-animation-bob attachment-large size-large wp-image-1520\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-1200x800.jpg 1200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4-1536x1024.jpg 1536w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-4.jpg 1800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14de2fc elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"14de2fc\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17c74a4 elementor-widget__width-initial elementor-absolute elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"17c74a4\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"242\" height=\"214\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/01\/dots-green.png\" class=\"attachment-large size-large wp-image-14\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d720f3\" data-id=\"9d720f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f3728 elementor-widget elementor-widget-heading\" data-id=\"c8f3728\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Why take this tour?<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-585df21 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"585df21\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">In Canyoning you can descend in waterfalls of 5m-15m-30m up to 40 meters high.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">You can do extreme sports in the morning and in the afternoon hike to Pailon del Diablo or visit the swing at the end of the world - tree house (you can choose waterfall or tree house).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">They can stay in Ba\u00f1os for more activities or return to Riobamba.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">VIP Tours, Hotel-Hotel.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8396d elementor-widget elementor-widget-heading\" data-id=\"fd8396d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Price<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5900fbf elementor-widget elementor-widget-text-editor\" data-id=\"5900fbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Contact us on WhatsApp: <a href=\"https:\/\/api.whatsapp.com\/send?phone=593998236014&amp;text=&amp;source=&amp;data=\">(+593) 99-823-6014<\/a><\/li><li>Minimum 2 persons.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d00c2ee elementor-widget elementor-widget-heading\" data-id=\"d00c2ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Duration<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d164a0b elementor-widget elementor-widget-text-editor\" data-id=\"d164a0b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>From 8am - 17:00pm from your Hotel in Riobamba.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b024c3 elementor-button-success elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1b024c3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form-reservar\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BOOK NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e405fa elementor-widget elementor-widget-spacer\" data-id=\"1e405fa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0ddb4b caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0ddb4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c893982\" data-id=\"c893982\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50a576f elementor-widget elementor-widget-heading\" data-id=\"50a576f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Itinerary<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78f609c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"78f609c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bf18ea\" data-id=\"7bf18ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6c0476 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b6c0476\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">08:00 The trip starts at your hotel in Riobamba or designated place.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">09:00 Arrival at Ba\u00f1os to try on the equipment such as wetsuit, helmet, shoes and harness.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">09:40 Arrival at the canyon for canyoning.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">13:00 Lunch.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a941dc\" data-id=\"2a941dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ca8450 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1ca8450\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-421 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ca8450\" data-elementor-lightbox-title=\"banner-inclinado-rio-rio-blanco\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MiwidXJsIjoiaHR0cHM6XC9cL2VjdWFkb3JhZHZlbnR1cmVzdHJpcC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9iYW5uZXItaW5jbGluYWRvLXJpby1yaW8tYmxhbmNvLmpwZyIsInNsaWRlc2hvdyI6IjFjYTg0NTAifQ%3D%3D\" data-rel=\"iLightbox[postimages]\" data-title=\"banner-inclinado-rio-rio-blanco\" data-caption=\"\" href='https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-200x133.jpg 200w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-300x200.jpg 300w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-400x267.jpg 400w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-600x400.jpg 600w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-768x512.jpg 768w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-800x533.jpg 800w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco-1024x683.jpg 1024w, https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-inclinado-rio-rio-blanco.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b983a54 caja-opciones elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b983a54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-51a50f7\" data-id=\"51a50f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c7705c elementor-widget elementor-widget-heading\" data-id=\"0c7705c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">End of the world swing option <br>(tree house)<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b57539d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b57539d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">15:00 Visit to the highest swing in Ecuador Fantasies of Flying or Flight of the Condor (not included).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">16:00 Visit to the end of the world swing or tree house.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">On the way back we visit a candy and sweets store.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">18:00 Arrival in Riobamba.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f6e62c9\" data-id=\"f6e62c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-503b8e2 elementor-widget elementor-widget-heading\" data-id=\"503b8e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pailon del Diablo Option<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3bcc62 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"b3bcc62\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96ecd4e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"96ecd4e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">15:00 Hike to the Pail\u00f3n del Diablo waterfall.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">16:00 Visit to the Pail\u00f3n del Diablo bridge viewpoint.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">On the way back we visit a candy and sweets store.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">18:00 Arrival in Riobamba.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a12cf50 caja-contenido-salidas elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a12cf50\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d0210b\" data-id=\"7d0210b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc342a2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cc342a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-50dad1c\" data-id=\"50dad1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67729df elementor-widget elementor-widget-text-editor\" data-id=\"67729df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Outputs:<\/h2><p>Every day, by reservation.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f5aba18\" data-id=\"f5aba18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-434297a elementor-widget elementor-widget-text-editor\" data-id=\"434297a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Includes:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79d07b9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"79d07b9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Private transportation from Riobamba-Ba\u00f1os and back.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tourist Guide.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Canyoning.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lunch.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrance fees to the indicated places.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-510710d\" data-id=\"510710d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da2367e elementor-widget elementor-widget-text-editor\" data-id=\"da2367e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>Does not include:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c309029 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c309029\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Swing fantasies of flying or flight of the condor.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tips.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Snacks.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dfbfdf caja-contenido elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dfbfdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8cf399\" data-id=\"f8cf399\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-09d3351 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"09d3351\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-17722fc\" data-id=\"17722fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26fb187 elementor-widget elementor-widget-text-editor\" data-id=\"26fb187\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>How to book:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38a7c61 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"38a7c61\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Send a WhatsApp to (+593) 99-823-6014 or an email to info@ecuadoradventurestrip.com with the following specifications: Name of the tour, date of the tour, number of people, first and last name, ID or passport number, city or country of origin.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Once we receive the information we will coordinate the details of the trip and payment methods.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">The payment must be made with the advance payment of 50% of the value. Do not forget to send proof of payment to WhatsApp (+593) 99-823-6014 or email info@ecuadortravelstrip.com.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2c89db elementor-widget elementor-widget-text-editor\" data-id=\"c2c89db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>What to bring:<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311efb9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"311efb9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bring a change of clothes, towel, slippers.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comfortable walking shoes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comfortable and light clothing.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hat, sunglasses, insect repellent, sunscreen, a light backpack to keep towel and small things.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5e0d635\" data-id=\"5e0d635\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47df765 caja-formulario-tours\" data-id=\"47df765\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6699498 elementor-widget elementor-widget-text-editor\" data-id=\"6699498\" data-element_type=\"widget\" id=\"form-reservar\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2><strong><span style=\"color: #0000ff;\">Book now<\/span><\/strong><\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3421dc elementor-widget elementor-widget-text-editor\" data-id=\"b3421dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f807-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"807\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wp-json\/wp\/v2\/pages\/421\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact Form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/421#wpcf7-f807-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"807\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f807-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.3\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name *\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"correo\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email *\" value=\"\" type=\"email\" name=\"correo\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone *\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"fecha\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required walcf7-datepicker\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Date: 0000-00-00 *\" value=\"\" type=\"text\" name=\"fecha\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"adultos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adults *\" value=\"\" type=\"text\" name=\"adultos\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ninnos\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Children: under 10 y.o. *\" value=\"\" type=\"text\" name=\"ninnos\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"comentarios\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Comments\" value=\"\" type=\"text\" name=\"comentarios\" \/><\/span>\n<\/p>\n<p>Type this code: <input type=\"hidden\" name=\"_wpcf7_captcha_challenge_captcha-1\" value=\"3584846628\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wpcf7-form-control wpcf7-captchac wpcf7-captcha-captcha-1\" width=\"72\" height=\"24\" alt=\"captcha\" src=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/wpcf7_captcha\/3584846628.png\" \/><span class=\"wpcf7-form-control-wrap\" data-name=\"captcha-1\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-captchar\" autocomplete=\"off\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"captcha-1\" \/><\/span>\n<\/p>\n<span class=\"wpcf7-form-control-wrap tour\" data-name=\"tour\"><input type=\"hidden\" name=\"tour\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Tour Canyoning Rio Blanco\"><\/span>\n<p>* Required fields\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enquire\" \/>\n<\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Close\">\u00d7<\/button><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Canyoning Rio Blanco - Ba\u00f1os Why take this tour? [...]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-421","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecuadoradventurestrip.com\/en\/rio-blanco-canyoning-tour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip\" \/>\n<meta property=\"og:description\" content=\"Canyoning Rio Blanco &#8211; Ba\u00f1os \u00bfPor qu\u00e9 tomar este tour? [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecuadoradventurestrip.com\/en\/rio-blanco-canyoning-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo - Ecuador Adventures Trip\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ecuadoradventurestrip\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-22T16:42:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/\",\"name\":\"Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip\",\"isPartOf\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg\",\"datePublished\":\"2021-01-28T19:43:19+00:00\",\"dateModified\":\"2021-03-22T16:42:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ecuadoradventurestrip.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour Canyoning Rio Blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#website\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"description\":\"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador\",\"publisher\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#organization\",\"name\":\"Turismo - Ecuador Adventures Trip\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png\",\"width\":5000,\"height\":5000,\"caption\":\"Turismo - Ecuador Adventures Trip\"},\"image\":{\"@id\":\"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ecuadoradventurestrip\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecuadoradventurestrip.com\/en\/rio-blanco-canyoning-tour\/","og_locale":"en_US","og_type":"article","og_title":"Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip","og_description":"Canyoning Rio Blanco &#8211; Ba\u00f1os \u00bfPor qu\u00e9 tomar este tour? [&hellip;]","og_url":"https:\/\/ecuadoradventurestrip.com\/en\/rio-blanco-canyoning-tour\/","og_site_name":"Turismo - Ecuador Adventures Trip","article_publisher":"https:\/\/www.facebook.com\/ecuadoradventurestrip","article_modified_time":"2021-03-22T16:42:41+00:00","og_image":[{"url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/","url":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/","name":"Tour Canyoning Rio Blanco - Turismo - Ecuador Adventures Trip","isPartOf":{"@id":"https:\/\/ecuadoradventurestrip.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage"},"thumbnailUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg","datePublished":"2021-01-28T19:43:19+00:00","dateModified":"2021-03-22T16:42:41+00:00","breadcrumb":{"@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#primaryimage","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/banner-rioblanco-1-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ecuadoradventurestrip.com\/tour-canyoning-rio-blanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecuadoradventurestrip.com\/"},{"@type":"ListItem","position":2,"name":"Tour Canyoning Rio Blanco"}]},{"@type":"WebSite","@id":"https:\/\/ecuadoradventurestrip.com\/#website","url":"https:\/\/ecuadoradventurestrip.com\/","name":"Turismo - Ecuador Adventures Trip","description":"Turismo - Ecuador Adventures Trip - Guia privado de turismo en Ecuador","publisher":{"@id":"https:\/\/ecuadoradventurestrip.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecuadoradventurestrip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ecuadoradventurestrip.com\/#organization","name":"Turismo - Ecuador Adventures Trip","url":"https:\/\/ecuadoradventurestrip.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/","url":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/ecuadoradventurestrip.com\/wp-content\/uploads\/2021\/03\/logofinal-fondo-transparente_Mesa-de-trabajo-1.png","width":5000,"height":5000,"caption":"Turismo - Ecuador Adventures Trip"},"image":{"@id":"https:\/\/ecuadoradventurestrip.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ecuadoradventurestrip"]}]}},"_links":{"self":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":0,"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/pages\/421\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecuadoradventurestrip.com\/en\/wp-json\/wp\/v2\/media?parent=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}